{"id":854,"date":"2020-12-04T12:03:22","date_gmt":"2020-12-04T15:03:22","guid":{"rendered":"https:\/\/psicologanoeliapettine.com\/?p=854"},"modified":"2020-12-04T12:03:22","modified_gmt":"2020-12-04T15:03:22","slug":"bullying-tipos-causas-y-consecuencias","status":"publish","type":"post","link":"https:\/\/dev.tumejorversiononline.com\/en\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/","title":{"rendered":"Qu\u00e9 es el bullying: 6 tipos de maltratos"},"content":{"rendered":"<h2 class=\"has-text-color wp-block-heading\" style=\"color:#e94577\">Qu\u00e9 es el bullying<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Bullying es una intimidaci\u00f3n, un acoso psicol\u00f3gico que se da en forma met\u00f3dica y sistem\u00e1tica<\/strong> en donde hay un agresor, una victima y c\u00f3mplices o espectadores que suelen festejar los actos del agresor d\u00e1ndole mayor poder e impunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El acoso escolar (tambi\u00e9n conocido como hostigamiento o maltrato escolar), es cualquier forma de maltrato psicol\u00f3gico verbal o f\u00edsico producido entre estudiantes de forma reiterada.<\/strong> Suele darse en el colegio como afuera de este y as\u00ed tambi\u00e9n en las redes sociales (cyber acoso). La etapa en la que mayoritariamente se da es en la adolescencia, aunque tambi\u00e9n puede darse entre ni\u00f1os o ni\u00f1as.<\/p>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#e94577\"><strong><u>6 Tipos de BULLYING<\/u><\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\"><li><strong>Maltrato f\u00edsico<\/strong>: Es el m\u00e1s visible. Se trata de golpes, empujones e incluso paliza entre uno o varios agresores sobre la v\u00edctima.<\/li><li><strong>Maltrato psicol\u00f3gico<\/strong>: Se trata de una manipulaci\u00f3n, intimidaciones, chantaje emocional y amenazas. Todos recaen sobre la v\u00edctima. Puede ser un gesto, una mirada o una se\u00f1al intimidatoria.<\/li><li><strong>Maltrato verbal:<\/strong> La finalidad es difundir una mala imagen de la v\u00edctima. Podr\u00eda ser por discriminaci\u00f3n, difundir falsos rumores, hacer bromas de mal gusto, entre otros.<\/li><li><strong>Maltrato sexual<\/strong>: Se puede dar por burlas sobre la orientaci\u00f3n sexual de la v\u00edctima (real o fantaseada) como referencias mal intencionadas sobre partes \u00edntimas de la v\u00edctima, hasta pudiendo llegar a la inducci\u00f3n o el abuso sexual.<\/li><li><strong>Bullying social<\/strong>: Se trata de excluir a la victima de todos los grupos, logrando la soledad del ni\u00f1o o adolescente.<\/li><li><strong>Bullying cibern\u00e9tico:<\/strong> Es el m\u00e1s reciente y peligroso dado el alcance que tienen las redes sociales. Son actos de humillaci\u00f3n, mensajes mentirosos que apuntan a dejar expuesta a la victima a la mirada burlona de gran cantidad de personas.<\/li><\/ol>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#e94577\"><u>Consecuencias del BULLYING para la v\u00edctima<\/u><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es quien sufre las mayores consecuencias. Lo que se observa en un chico\/a que sufre BULLYNG es:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a aria-label=\"Baja autoestima\u2028 (opens in a new tab)\" href=\"https:\/\/tumejorversiononline.com\/como-mejorar-la-autoestima\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"rank-math-link\">Baja autoestima<\/a><\/li><li>Problemas psicosom\u00e1ticos<\/li><li>Actitudes de retraimiento<\/li><li>Culpa<\/li><li><a aria-label=\"Angustia (opens in a new tab)\" href=\"https:\/\/tumejorversiononline.com\/estado-de-angustia\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"rank-math-link\">Angustia<\/a><\/li><li>Bajo rendimiento escolar<\/li><li>Deserci\u00f3n escolar<\/li><li><a href=\"https:\/\/tumejorversiononline.com\/que-es-la-depresion-y-sus-sintomas\/\" target=\"_blank\" aria-label=\"Depresi\u00f3n (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"rank-math-link\">Depresi\u00f3n<\/a><\/li><li>Inestabilidad emocional<\/li><li>Aislamiento social y\/o familiar<\/li><li>Suicidio<\/li><\/ul>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#e94577\"><u>Causas y consecuencias del BULLYING para el agresor<\/u><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las causas que explican esta conducta pueden ser: Violencia familiar, abandono, carencias emocionales, personalidad psicop\u00e1tica. Tambi\u00e9n pueden encontrarse situaciones en la que cuesta explicar el origen de la conducta.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus consecuencias pueden ser:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Falta de control<\/li><li>Actitud violenta, intolerable, desafiante e impulsiva<\/li><li>Muestra de autoridad exagerada<\/li><li>Actitud amenazante o de imposici\u00f3n<\/li><li>Perdida de inter\u00e9s en la escuela<\/li><li>Fracaso escolar<\/li><li>Relaciones sociales y familiares problem\u00e1ticas<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las consecuencias para la masa silenciosa pueden ser: Miedos, abatimiento al considerar que ellos no pueden hacer nada para cambiar la situaci\u00f3n, culpa, <a href=\"https:\/\/tumejorversiononline.com\/sintomas-de-una-crisis-emocional\/\" target=\"_blank\" aria-label=\"crisis emocionales (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"rank-math-link\">crisis emocionales<\/a>.<\/strong><\/p>\n\n\n\n<h2 class=\"has-text-color wp-block-heading\" style=\"color:#e94577\"><u>C\u00f3mo prevenir el BULLYING<\/u><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lo m\u00e1s importante comienza por casa. Es fundamental conocer a nuestros hijos para poder detectar cambios de conducta.<\/strong> Promulgar el dialogo para que los ni\u00f1os sientan confianza de poder decir lo que les sucede. Tambi\u00e9n es importante practicar el respeto por el otro, ser tolerante, hablar con la verdad, practicar la humildad y ser emp\u00e1tico.<\/p>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#e94577\"><strong><u>Conclusiones<\/u><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El BULLYING es m\u00e1s com\u00fan de lo que se supone. Si sospechas que a tu hijo le est\u00e1 sucediendo o vez cambios de conductas en \u00e9l, como por ejemplo que no quiera ir a la escuela, no dejes de preguntar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si ten\u00e9s conocimiento que algo as\u00ed sucede no dudes en hablar con las autoridades de la instituci\u00f3n. Hay que frenarlo cuanto antes ya que es de alto riesgo para los ni\u00f1os o adolescentes.<\/p>","protected":false},"excerpt":{"rendered":"<p>Qu\u00e9 es el bullying El Bullying es una intimidaci\u00f3n, un acoso psicol\u00f3gico que se da en forma met\u00f3dica y sistem\u00e1tica en donde hay un agresor, una victima y c\u00f3mplices o espectadores que suelen festejar los actos del agresor d\u00e1ndole mayor poder e impunidad. El acoso escolar (tambi\u00e9n conocido como hostigamiento o maltrato escolar), es cualquier [&hellip;]<\/p>","protected":false},"author":2,"featured_media":1946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[13],"tags":[50,14],"class_list":["post-854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-psicologo-en-linea","tag-bullying","tag-psicologo-online"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu\u00e9 es el bullying: 6 tipos de maltratos - TU MEJOR VERSI\u00d3N ONLINE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.tumejorversiononline.com\/en\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 es el bullying: 6 tipos de maltratos - TU MEJOR VERSI\u00d3N ONLINE\" \/>\n<meta property=\"og:description\" content=\"Qu\u00e9 es el bullying El Bullying es una intimidaci\u00f3n, un acoso psicol\u00f3gico que se da en forma met\u00f3dica y sistem\u00e1tica en donde hay un agresor, una victima y c\u00f3mplices o espectadores que suelen festejar los actos del agresor d\u00e1ndole mayor poder e impunidad. El acoso escolar (tambi\u00e9n conocido como hostigamiento o maltrato escolar), es cualquier [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.tumejorversiononline.com\/en\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/\" \/>\n<meta property=\"og:site_name\" content=\"TU MEJOR VERSI\u00d3N ONLINE\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-04T15:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.tumejorversiononline.com\/wp-content\/uploads\/2020\/12\/bullying-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noelia Pettine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noelia Pettine\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/\",\"url\":\"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/\",\"name\":\"Qu\u00e9 es el bullying: 6 tipos de maltratos - TU MEJOR VERSI\u00d3N ONLINE\",\"isPartOf\":{\"@id\":\"https:\/\/dev.tumejorversiononline.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.tumejorversiononline.com\/wp-content\/uploads\/2020\/12\/bullying-1.jpg\",\"datePublished\":\"2020-12-04T15:03:22+00:00\",\"author\":{\"@id\":\"https:\/\/dev.tumejorversiononline.com\/#\/schema\/person\/b7035f0cda83692bbb388ef8e4779934\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#primaryimage\",\"url\":\"https:\/\/dev.tumejorversiononline.com\/wp-content\/uploads\/2020\/12\/bullying-1.jpg\",\"contentUrl\":\"https:\/\/dev.tumejorversiononline.com\/wp-content\/uploads\/2020\/12\/bullying-1.jpg\",\"width\":640,\"height\":425,\"caption\":\"bullying\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/dev.tumejorversiononline.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 es el bullying: 6 tipos de maltratos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.tumejorversiononline.com\/#website\",\"url\":\"https:\/\/dev.tumejorversiononline.com\/\",\"name\":\"TU MEJOR VERSI\u00d3N ONLINE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.tumejorversiononline.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.tumejorversiononline.com\/#\/schema\/person\/b7035f0cda83692bbb388ef8e4779934\",\"name\":\"Noelia Pettine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.tumejorversiononline.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/86f331155465c6d5880e76598411628ddf00aa51e155363e0c83d283f9b2cc93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/86f331155465c6d5880e76598411628ddf00aa51e155363e0c83d283f9b2cc93?s=96&d=mm&r=g\",\"caption\":\"Noelia Pettine\"},\"url\":\"https:\/\/dev.tumejorversiononline.com\/en\/author\/noelia_pettine_admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 es el bullying: 6 tipos de maltratos - TU MEJOR VERSI\u00d3N ONLINE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.tumejorversiononline.com\/en\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/","og_locale":"en_US","og_type":"article","og_title":"Qu\u00e9 es el bullying: 6 tipos de maltratos - TU MEJOR VERSI\u00d3N ONLINE","og_description":"Qu\u00e9 es el bullying El Bullying es una intimidaci\u00f3n, un acoso psicol\u00f3gico que se da en forma met\u00f3dica y sistem\u00e1tica en donde hay un agresor, una victima y c\u00f3mplices o espectadores que suelen festejar los actos del agresor d\u00e1ndole mayor poder e impunidad. El acoso escolar (tambi\u00e9n conocido como hostigamiento o maltrato escolar), es cualquier [&hellip;]","og_url":"https:\/\/dev.tumejorversiononline.com\/en\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/","og_site_name":"TU MEJOR VERSI\u00d3N ONLINE","article_published_time":"2020-12-04T15:03:22+00:00","og_image":[{"width":640,"height":425,"url":"https:\/\/dev.tumejorversiononline.com\/wp-content\/uploads\/2020\/12\/bullying-1.jpg","type":"image\/jpeg"}],"author":"Noelia Pettine","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Noelia Pettine","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/","url":"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/","name":"Qu\u00e9 es el bullying: 6 tipos de maltratos - TU MEJOR VERSI\u00d3N ONLINE","isPartOf":{"@id":"https:\/\/dev.tumejorversiononline.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#primaryimage"},"image":{"@id":"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.tumejorversiononline.com\/wp-content\/uploads\/2020\/12\/bullying-1.jpg","datePublished":"2020-12-04T15:03:22+00:00","author":{"@id":"https:\/\/dev.tumejorversiononline.com\/#\/schema\/person\/b7035f0cda83692bbb388ef8e4779934"},"breadcrumb":{"@id":"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#primaryimage","url":"https:\/\/dev.tumejorversiononline.com\/wp-content\/uploads\/2020\/12\/bullying-1.jpg","contentUrl":"https:\/\/dev.tumejorversiononline.com\/wp-content\/uploads\/2020\/12\/bullying-1.jpg","width":640,"height":425,"caption":"bullying"},{"@type":"BreadcrumbList","@id":"https:\/\/dev.tumejorversiononline.com\/2020\/12\/04\/bullying-tipos-causas-y-consecuencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/dev.tumejorversiononline.com\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 es el bullying: 6 tipos de maltratos"}]},{"@type":"WebSite","@id":"https:\/\/dev.tumejorversiononline.com\/#website","url":"https:\/\/dev.tumejorversiononline.com\/","name":"TU MEJOR VERSI\u00d3N ONLINE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.tumejorversiononline.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/dev.tumejorversiononline.com\/#\/schema\/person\/b7035f0cda83692bbb388ef8e4779934","name":"Noelia Pettine","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.tumejorversiononline.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/86f331155465c6d5880e76598411628ddf00aa51e155363e0c83d283f9b2cc93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/86f331155465c6d5880e76598411628ddf00aa51e155363e0c83d283f9b2cc93?s=96&d=mm&r=g","caption":"Noelia Pettine"},"url":"https:\/\/dev.tumejorversiononline.com\/en\/author\/noelia_pettine_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/posts\/854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/comments?post=854"}],"version-history":[{"count":0,"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/posts\/854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/media\/1946"}],"wp:attachment":[{"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/media?parent=854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/categories?post=854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.tumejorversiononline.com\/en\/wp-json\/wp\/v2\/tags?post=854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}